{"id":468,"date":"2023-09-12T10:10:36","date_gmt":"2023-09-12T10:10:36","guid":{"rendered":"https:\/\/wordpress-969684-3873137.cloudwaysapps.com\/?post_type=faqs&#038;p=468"},"modified":"2023-09-12T10:10:37","modified_gmt":"2023-09-12T10:10:37","slug":"ich-habe-einen-falschen-finanzeintrag-gemacht-kann-ich-diesen-loeschen","status":"publish","type":"faqs","link":"https:\/\/www.flatify-app.com\/en\/faqs\/ich-habe-einen-falschen-finanzeintrag-gemacht-kann-ich-diesen-loeschen\/","title":{"rendered":"Ich habe einen falschen Finanzeintrag gemacht. Kann ich diesen l\u00f6schen?"},"content":{"rendered":"\n<p>Nat\u00fcrlich kann es mal vorkommen, dass du einen Finanzeintrag falsch erstellt hast. Hier hast du selbstverst\u00e4ndlich die M\u00f6glichkeit, diesen Eintrag zu l\u00f6schen um diesen danach wieder neu erstellen zu k\u00f6nnen.<\/p>\n\n\n\n<ol>\n<li>Gehe auf die \u00dcbersichtsseite und klicke auf den Punkt \u201eFinanzen\u201c<\/li>\n\n\n\n<li>Nun wird dir eine Liste aller Zahlungen angezeigt, die get\u00e4tigt wurden.<\/li>\n\n\n\n<li>Solltest du kein Flatify Plus haben, wird dir hier nur die letzte Zahlung angezeigt.<\/li>\n\n\n\n<li>Um den Eintrag zu l\u00f6schen, dr\u00fcckst du nun auf den gew\u00fcnschten Finanzeintrag.<\/li>\n\n\n\n<li>Nun erscheint unten ein kleines Fenster mit \u201eZahlung l\u00f6schen\u201c<\/li>\n\n\n\n<li>Klicke dieses und der Finanzeintrag ist gel\u00f6scht.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Nat\u00fcrlich kann es mal vorkommen, dass du einen Finanzeintrag falsch erstellt hast. Hier hast du selbstverst\u00e4ndlich die M\u00f6glichkeit, diesen Eintrag zu l\u00f6schen um diesen danach wieder neu erstellen zu k\u00f6nnen.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","faqcategories":[24],"_links":{"self":[{"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/faqs\/468"}],"collection":[{"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/faqs"}],"about":[{"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/types\/faqs"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/comments?post=468"}],"wp:attachment":[{"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/media?parent=468"}],"wp:term":[{"taxonomy":"faqcategories","embeddable":true,"href":"https:\/\/www.flatify-app.com\/en\/wp-json\/wp\/v2\/faqcategories?post=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}