{"id":723,"date":"2023-09-24T05:28:02","date_gmt":"2023-09-24T05:28:02","guid":{"rendered":"https:\/\/wordpress-969684-3873137.cloudwaysapps.com\/?post_type=faqs&#038;p=723"},"modified":"2024-04-15T19:16:33","modified_gmt":"2024-04-15T19:16:33","slug":"wie-kann-ich-meinen-account-loeschen","status":"publish","type":"faqs","link":"https:\/\/www.flatify-app.com\/nl\/faqs\/wie-kann-ich-meinen-account-loeschen\/","title":{"rendered":"Wie kann ich meinen Flatify Account l\u00f6schen?"},"content":{"rendered":"\n<p>Du m\u00f6chtest deinen Account bei Flatify und deine Daten l\u00f6schen? Das finden wir nat\u00fcrlich schade, aber nat\u00fcrlich ist es kein Problem. Dazu gehst du wie folgt vor:<\/p>\n\n\n\n<p>1. Gehe in der App auf Einstellungen<\/p>\n\n\n\n<p>2.\u00a0 Scrolle ganz runter auf &#8222;Account l\u00f6schen&#8220;<\/p>\n\n\n\n<p>Dein Account und deine Daten werden dann&nbsp; unwiederruflich aus unserem System gel\u00f6scht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du m\u00f6chtest deinen Account bei Flatify und deine Daten l\u00f6schen? Das finden wir nat\u00fcrlich schade, aber nat\u00fcrlich ist es kein Problem. Dazu gehst du wie folgt vor: 1. Gehe in der App auf Einstellungen 2.\u00a0 Scrolle ganz runter auf &#8222;Account l\u00f6schen&#8220; Dein Account und deine Daten werden dann&nbsp; unwiederruflich aus unserem System gel\u00f6scht.<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","faqcategories":[21],"_links":{"self":[{"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/faqs\/723"}],"collection":[{"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/faqs"}],"about":[{"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/types\/faqs"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/comments?post=723"}],"wp:attachment":[{"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/media?parent=723"}],"wp:term":[{"taxonomy":"faqcategories","embeddable":true,"href":"https:\/\/www.flatify-app.com\/nl\/wp-json\/wp\/v2\/faqcategories?post=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}